{"id":3600,"date":"2022-07-26T13:53:18","date_gmt":"2022-07-26T11:53:18","guid":{"rendered":"https:\/\/degussa-staging.detail-digital.ch\/?page_id=3600"},"modified":"2022-08-03T21:13:15","modified_gmt":"2022-08-03T19:13:15","slug":"your-sale-to-us","status":"publish","type":"page","link":"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us","title":{"rendered":"Your sale to us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3600\" class=\"elementor elementor-3600\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce2adcb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce2adcb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63100b8\" data-id=\"63100b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fb1734 elementor-widget elementor-widget-subnav\" data-id=\"0fb1734\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"subnav.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"degussa-subnav-container subnav gold\">\n                            <div class=\"subnav-item\">\n                    <a href=\"https:\/\/www.degussa-mp.es\/de\/services\/schliessfaecher\">Schliessf\u00e4cher<\/a>\n                <\/div>\n                            <div class=\"subnav-item\">\n                    <a href=\"https:\/\/www.degussa-mp.es\/de\/services\/ihr-verkauf-an-uns\">Ihr Verkauf an uns<\/a>\n                <\/div>\n                            <div class=\"subnav-item\">\n                    <a href=\"https:\/\/www.degussa-mp.es\/de\/services\/service-altgold-ankauf\">Altgold<\/a>\n                <\/div>\n                            <div class=\"subnav-item\">\n                    <a href=\"https:\/\/www.degussa-mp.es\/de\/services\/service-praegung\">Pr\u00e4gung<\/a>\n                <\/div>\n            \n        <\/div>\n        <div class=\"degussa-subnav-container empty\"><\/div>\n\n\t\t        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9d56fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9d56fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebd4281\" data-id=\"ebd4281\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86f5d70 elementor-widget elementor-widget-heading\" data-id=\"86f5d70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">WE BUY YOUR BARS AND COINS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d936362 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d936362\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f3690cc\" data-id=\"f3690cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1062847 elementor-widget elementor-widget-contentstack\" data-id=\"1062847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"contentstack.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"content-stack\"><style>.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-widget-text-editor{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );color:var( --e-global-color-text );}.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:var( --e-global-color-primary );}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap, .elementor-widget-text-editor.elementor-drop-cap-view-default .elementor-drop-cap{color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-650 .elementor-element.elementor-element-fa42cbd .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-widget-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );}.elementor-650 .elementor-element.elementor-element-1776c42 img{width:100%;}@media(min-width:768px){.elementor-650 .elementor-element.elementor-element-a451f1f{width:66.756%;}.elementor-650 .elementor-element.elementor-element-22e259c{width:32.547%;}}@media(max-width:1024px){.elementor-widget-text-editor{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}}@media(max-width:767px){.elementor-widget-text-editor{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3318\" class=\"elementor elementor-3318 elementor-10302 elementor-10302\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-622a5e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"622a5e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a451f1f\" data-id=\"a451f1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96c6abb elementor-widget elementor-widget-heading\" data-id=\"96c6abb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BARS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21d60eb elementor-widget elementor-widget-text-editor\" data-id=\"21d60eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>As the largest precious metal dealer in Europe, we not only sell our Degussa bars, but also buy all investment bars and coins.<br \/>The sale of your bars and coins is possible at any time at our counter in Madrid. Unlike most banks, we do not only buy our own company bars, but all investment bars.<br \/>When selling your bars to us, it is not important for the bar certificate to be present or for the bars to be in perfect condition.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa42cbd elementor-widget elementor-widget-heading\" data-id=\"fa42cbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Coins<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-617f5ae elementor-widget elementor-widget-text-editor\" data-id=\"617f5ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>When we purchase coins such as Krugerrands or Maple Leaves, we differentiate between 1st and 2nd quality :<br><br>1st quality : The coin is in good condition and is eligible to be resold.<br>2nd quality : The coin has scratches or stains and must be smelted.<br><br><\/p>\n<p>The proceeds can be paid on the spot at the counter, or transferred to your bank account upon request.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-22e259c\" data-id=\"22e259c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1776c42 elementor-widget elementor-widget-image\" data-id=\"1776c42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/gold-barren-muenzen-vreneli-1024x683.jpg\" class=\"attachment-large size-large wp-image-6195\" alt=\"\" srcset=\"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/gold-barren-muenzen-vreneli-1024x683.jpg 1024w, https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/gold-barren-muenzen-vreneli-300x200.jpg 300w, https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/gold-barren-muenzen-vreneli-768x512.jpg 768w, https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/gold-barren-muenzen-vreneli.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"content-stack\"><style>.elementor-10405 .elementor-element.elementor-element-153d883d > .elementor-widget-wrap > .elementor-widget:not(.elementor-widget__width-auto):not(.elementor-widget__width-initial):not(:last-child):not(.elementor-absolute){margin-block-end:0px;}.elementor-widget-slides .elementor-slide-heading{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );}.elementor-widget-slides .elementor-slide-description{font-family:var( --e-global-typography-secondary-font-family ), Sans-serif;font-weight:var( --e-global-typography-secondary-font-weight );}.elementor-widget-slides .elementor-slide-button{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );}.elementor-10405 .elementor-element.elementor-element-a7ab720 .elementor-repeater-item-d0ba368 .swiper-slide-bg{background-color:#bbbbbb;background-image:url(https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/11\/ezgif-3-8ad4a8d3b3.gif);background-size:cover;}.elementor-10405 .elementor-element.elementor-element-a7ab720 .swiper-slide{height:400px;transition-duration:calc(5000ms*1.2);}.elementor-10405 .elementor-element.elementor-element-a7ab720 .swiper-slide-contents{max-width:66%;}.elementor-10405 .elementor-element.elementor-element-a7ab720 .swiper-slide-inner{text-align:center;}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3334\" class=\"elementor elementor-3334 elementor-10405 elementor-10405\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17a8ef24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17a8ef24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3395bf74\" data-id=\"3395bf74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-16d7ad09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16d7ad09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-153d883d\" data-id=\"153d883d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7ab720 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"a7ab720\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper-container\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-d0ba368 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e078a64 elementor-widget elementor-widget-slidercontext\" data-id=\"e078a64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"slidercontext.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"degussa-product-slider-outer-container nopadding\">\n            <div class=\"degussa-slider-context\">\n                <div class=\"slider-title\">Globally networked<\/div>\n                <div class=\"slider-actions\">\n                    <a class=\"context-link\" href=\"\/en\/locations\"><span>Locations<\/span>\n                        <\/a><a class=\"context-link\" href=\"\/en\/trust\/memberships\"><span>Memberships<\/span>\n                        <\/a><a class=\"context-link\" href=\"\/en\/trust\/partnerships\"><span>Partnerships<\/span>\n                        <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Safe deposit boxes Lombard loan We buy your bars and coins Customs warehouse We buy old gold Customized minting WE BUY YOUR BARS AND COINS Edit in Elementor BARS As the largest precious metal dealer in Europe, we not only sell our Degussa bars, but also buy all investment bars and coins. The purchase of [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3390,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3600","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Your sale to us - Degussa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Your sale to us - Degussa\" \/>\n<meta property=\"og:description\" content=\"Safe deposit boxes Lombard loan We buy your bars and coins Customs warehouse We buy old gold Customized minting WE BUY YOUR BARS AND COINS Edit in Elementor BARS As the largest precious metal dealer in Europe, we not only sell our Degussa bars, but also buy all investment bars and coins. The purchase of [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us\" \/>\n<meta property=\"og:site_name\" content=\"Degussa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-03T19:13:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/barren-verkaufen-degussa-goldhandel-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us\",\"url\":\"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us\",\"name\":\"Your sale to us - Degussa\",\"isPartOf\":{\"@id\":\"https:\/\/www.degussa-mp.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/barren-verkaufen-degussa-goldhandel-1.jpg\",\"datePublished\":\"2022-07-26T11:53:18+00:00\",\"dateModified\":\"2022-08-03T19:13:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us#primaryimage\",\"url\":\"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/barren-verkaufen-degussa-goldhandel-1.jpg\",\"contentUrl\":\"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/barren-verkaufen-degussa-goldhandel-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.degussa-mp.es\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\/\/www.degussa-mp.es\/en\/services\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Your sale to us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.degussa-mp.es\/#website\",\"url\":\"https:\/\/www.degussa-mp.es\/\",\"name\":\"Degussa\",\"description\":\"ESPECIALISTAS EN METALES PRECIOSOS\",\"publisher\":{\"@id\":\"https:\/\/www.degussa-mp.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.degussa-mp.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.degussa-mp.es\/#organization\",\"name\":\"Degussa\",\"url\":\"https:\/\/www.degussa-mp.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.degussa-mp.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/04\/Degussa-Goldhandel-Logo.svg\",\"contentUrl\":\"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/04\/Degussa-Goldhandel-Logo.svg\",\"caption\":\"Degussa\"},\"image\":{\"@id\":\"https:\/\/www.degussa-mp.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Your sale to us - Degussa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us","og_locale":"en_US","og_type":"article","og_title":"Your sale to us - Degussa","og_description":"Safe deposit boxes Lombard loan We buy your bars and coins Customs warehouse We buy old gold Customized minting WE BUY YOUR BARS AND COINS Edit in Elementor BARS As the largest precious metal dealer in Europe, we not only sell our Degussa bars, but also buy all investment bars and coins. The purchase of [&hellip;]","og_url":"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us","og_site_name":"Degussa","article_modified_time":"2022-08-03T19:13:15+00:00","og_image":[{"url":"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/barren-verkaufen-degussa-goldhandel-1.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us","url":"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us","name":"Your sale to us - Degussa","isPartOf":{"@id":"https:\/\/www.degussa-mp.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us#primaryimage"},"image":{"@id":"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us#primaryimage"},"thumbnailUrl":"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/barren-verkaufen-degussa-goldhandel-1.jpg","datePublished":"2022-07-26T11:53:18+00:00","dateModified":"2022-08-03T19:13:15+00:00","breadcrumb":{"@id":"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us#primaryimage","url":"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/barren-verkaufen-degussa-goldhandel-1.jpg","contentUrl":"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/05\/barren-verkaufen-degussa-goldhandel-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.degussa-mp.es\/en\/services\/your-sale-to-us#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.degussa-mp.es\/en"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/www.degussa-mp.es\/en\/services"},{"@type":"ListItem","position":3,"name":"Your sale to us"}]},{"@type":"WebSite","@id":"https:\/\/www.degussa-mp.es\/#website","url":"https:\/\/www.degussa-mp.es\/","name":"Degussa","description":"ESPECIALISTAS EN METALES PRECIOSOS","publisher":{"@id":"https:\/\/www.degussa-mp.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.degussa-mp.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.degussa-mp.es\/#organization","name":"Degussa","url":"https:\/\/www.degussa-mp.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.degussa-mp.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/04\/Degussa-Goldhandel-Logo.svg","contentUrl":"https:\/\/www.degussa-mp.es\/wp-content\/uploads\/2022\/04\/Degussa-Goldhandel-Logo.svg","caption":"Degussa"},"image":{"@id":"https:\/\/www.degussa-mp.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.degussa-mp.es\/en\/wp-json\/wp\/v2\/pages\/3600"}],"collection":[{"href":"https:\/\/www.degussa-mp.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.degussa-mp.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.degussa-mp.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.degussa-mp.es\/en\/wp-json\/wp\/v2\/comments?post=3600"}],"version-history":[{"count":8,"href":"https:\/\/www.degussa-mp.es\/en\/wp-json\/wp\/v2\/pages\/3600\/revisions"}],"predecessor-version":[{"id":4003,"href":"https:\/\/www.degussa-mp.es\/en\/wp-json\/wp\/v2\/pages\/3600\/revisions\/4003"}],"up":[{"embeddable":true,"href":"https:\/\/www.degussa-mp.es\/en\/wp-json\/wp\/v2\/pages\/3390"}],"wp:attachment":[{"href":"https:\/\/www.degussa-mp.es\/en\/wp-json\/wp\/v2\/media?parent=3600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}